{"id":1261709,"date":"2025-01-22T19:08:04","date_gmt":"2025-01-22T10:08:04","guid":{"rendered":"https:\/\/www.ena.co.jp\/ena-a1\/?p=1261709"},"modified":"2025-01-28T15:48:35","modified_gmt":"2025-01-28T06:48:35","slug":"%e3%80%90ena%e7%9b%ae%e7%99%bd%e3%83%bb%e5%8f%97%e9%a8%93%e7%9b%b4%e5%89%8d%e3%80%91%e3%82%82%e3%81%86%e3%81%99%e3%81%90%e6%96%b0%e5%ad%a6%e5%b9%b4","status":"publish","type":"post","link":"https:\/\/www.ena.co.jp\/ena-a1\/toshima-ku\/mejiro\/2025\/01\/22\/%e3%80%90ena%e7%9b%ae%e7%99%bd%e3%83%bb%e5%8f%97%e9%a8%93%e7%9b%b4%e5%89%8d%e3%80%91%e3%82%82%e3%81%86%e3%81%99%e3%81%90%e6%96%b0%e5%ad%a6%e5%b9%b4\/","title":{"rendered":"\u3010ena\u76ee\u767d\u30fb\u5165\u8a66\u76f4\u524d\uff01\u3011\u3082\u3046\u3059\u3050\u65b0\u5b66\u5e74"},"content":{"rendered":"<p><span style=\"font-family: 'arial black', sans-serif; font-size: 12pt;\"><strong>\u3053\u3093\u306b\u3061\u306f\uff01ena\u76ee\u767d\u306e\u85e4\u7530\u3067\u3059\u3002<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: 'arial black', sans-serif; font-size: 12pt;\"><strong>\u53d7\u9a13\u76f4\u524d\u671f\u9593\u3068\u3044\u3046\u3053\u3068\u306f\u3001<span style=\"color: #ff00ff;\">\u3082\u3046\u3059\u3050\u65b0\u5b66\u5e74\u3067\u3059\u306d\uff01<\/span><\/strong><\/span><\/p>\n<p><span style=\"font-family: 'arial black', sans-serif; font-size: 12pt;\"><strong>\u4eca\u5e74\u5ea6\u4e00\u5e74\u9593\u3068\u306f\u307e\u305f\u9055\u3063\u305f\u4e00\u5e74\u304c\u5f85\u3063\u3066\u3044\u308b\u3068\u601d\u3044\u307e\u3059\u3002<\/strong><\/span><\/p>\n<p><span style=\"font-family: 'arial black', sans-serif; font-size: 12pt;\"><strong>\u53d7\u9a13\u3092\u3059\u308b\u306b\u306f\u3001\u76f8\u5f53\u306a\u899a\u609f\u304c\u5fc5\u8981\u3067\u3059\u3002<\/strong><\/span><\/p>\n<p><span style=\"font-family: 'arial black', sans-serif; font-size: 12pt; color: #ff6600;\"><strong>\u5e74\u5ea6\u306e\u5207\u308a\u66ff\u308f\u308a\u3060\u304b\u3089\u3053\u305d\u3001\u6c17\u6301\u3061\u3092\u5f15\u304d\u7de0\u3081\u3066\u3001\u76ee\u306e\u524d\u306e\u52c9\u5f37\u306b\u53d6\u308a\u7d44\u3093\u3067\u3044\u304d\u307e\u3057\u3087\u3046\uff01<\/strong><\/span><\/p>\n<p><img loading=\"lazy\" class=\"aligncenter size-full wp-image-1261710\" src=\"https:\/\/www-ena-co-jp.s3.amazonaws.com\/ena-a1\/files\/2025\/01\/IMG_0647-1-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" \/> <img loading=\"lazy\" class=\"aligncenter size-full wp-image-1261711\" src=\"https:\/\/www-ena-co-jp.s3.amazonaws.com\/ena-a1\/files\/2025\/01\/IMG_0648-1-scaled.jpg\" alt=\"\" width=\"2560\" height=\"1920\" \/><\/p>\n<p><span style=\"font-family: 'arial black', sans-serif; font-size: 12pt;\"><strong>\u4eca\u65e5\u3082\u307f\u3093\u306a\u4e00\u751f\u61f8\u547d\u3067\u3059\uff01<\/strong><\/span><\/p>\n<p>\u305d\u308d\u305d\u308d\u304b\u306a\u3000\u85e4\u7530<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u3053\u3093\u306b\u3061\u306f\uff01ena\u76ee\u767d\u306e\u85e4\u7530\u3067\u3059\u3002 &nbsp; \u53d7\u9a13\u76f4\u524d\u671f\u9593\u3068\u3044\u3046\u3053\u3068\u306f\u3001\u3082\u3046\u3059\u3050\u65b0\u5b66\u5e74\u3067\u3059\u306d\uff01 \u4eca\u5e74\u5ea6\u4e00\u5e74\u9593\u3068\u306f\u307e\u305f\u9055\u3063\u305f\u4e00\u5e74\u304c\u5f85\u3063\u3066\u3044\u308b\u3068\u601d\u3044\u307e\u3059\u3002 \u53d7\u9a13\u3092\u3059\u308b\u306b\u306f\u3001\u76f8\u5f53\u306a\u899a\u609f\u304c\u5fc5\u8981\u3067\u3059\u3002 \u5e74\u5ea6\u306e\u5207\u308a\u66ff\u308f\u308a\u3060\u304b\u3089\u3053<\/p>\n<p><a href=\"https:\/\/www.ena.co.jp\/ena-a1\/toshima-ku\/mejiro\/2025\/01\/22\/%e3%80%90ena%e7%9b%ae%e7%99%bd%e3%83%bb%e5%8f%97%e9%a8%93%e7%9b%b4%e5%89%8d%e3%80%91%e3%82%82%e3%81%86%e3%81%99%e3%81%90%e6%96%b0%e5%ad%a6%e5%b9%b4\/\">\u3082\u3063\u3068\u8aad\u3080&#8230;<\/a><\/p>\n","protected":false},"author":55,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[8],"tags":[],"_links":{"self":[{"href":"https:\/\/www.ena.co.jp\/ena-a1\/wp-json\/wp\/v2\/posts\/1261709"}],"collection":[{"href":"https:\/\/www.ena.co.jp\/ena-a1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ena.co.jp\/ena-a1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ena.co.jp\/ena-a1\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ena.co.jp\/ena-a1\/wp-json\/wp\/v2\/comments?post=1261709"}],"version-history":[{"count":2,"href":"https:\/\/www.ena.co.jp\/ena-a1\/wp-json\/wp\/v2\/posts\/1261709\/revisions"}],"predecessor-version":[{"id":1263189,"href":"https:\/\/www.ena.co.jp\/ena-a1\/wp-json\/wp\/v2\/posts\/1261709\/revisions\/1263189"}],"wp:attachment":[{"href":"https:\/\/www.ena.co.jp\/ena-a1\/wp-json\/wp\/v2\/media?parent=1261709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ena.co.jp\/ena-a1\/wp-json\/wp\/v2\/categories?post=1261709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ena.co.jp\/ena-a1\/wp-json\/wp\/v2\/tags?post=1261709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}